{"id":10068,"date":"2023-12-04T13:21:15","date_gmt":"2023-12-04T16:21:15","guid":{"rendered":"https:\/\/www.didasantos.com.br\/v1\/?p=10068"},"modified":"2023-12-04T13:21:15","modified_gmt":"2023-12-04T16:21:15","slug":"tragedia-na-indonesia-vulcao-marapi-deixa-vitimas-e-desaparecidos-apos-erupcao","status":"publish","type":"post","link":"https:\/\/www.didasantos.com.br\/v1\/2023\/12\/04\/tragedia-na-indonesia-vulcao-marapi-deixa-vitimas-e-desaparecidos-apos-erupcao\/","title":{"rendered":"Trag\u00e9dia na Indon\u00e9sia: Vulc\u00e3o Marapi deixa v\u00edtimas e desaparecidos ap\u00f3s Erup\u00e7\u00e3o"},"content":{"rendered":"<div class=\"flex-1 overflow-hidden\">\n<div class=\"react-scroll-to-bottom--css-vfeuu-79elbk h-full\">\n<div class=\"react-scroll-to-bottom--css-vfeuu-1n7m0yu\">\n<div class=\"flex flex-col pb-9 text-sm\">\n<div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-90\">\n<div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\">\n<div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] } group final-completion\">\n<div class=\"relative flex w-full flex-col lg:w-[calc(100%-115px)] agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"6c8a87cb-9be0-4395-b303-bf8cf4f77602\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>Pelo menos 11 pessoas perderam a vida e outras 12 est\u00e3o desaparecidas ap\u00f3s a erup\u00e7\u00e3o do vulc\u00e3o Marapi, localizado na regi\u00e3o oeste da Indon\u00e9sia. Os servi\u00e7os de emerg\u00eancia confirmaram a situa\u00e7\u00e3o nesta segunda-feira (4), ap\u00f3s uma noite intensa de buscas, que resultaram no resgate de tr\u00eas montanhistas.<\/p>\n<p>No momento da erup\u00e7\u00e3o, ocorrida no domingo (3), havia 75 pessoas na \u00e1rea, das quais 26 n\u00e3o foram resgatadas a tempo, conforme informou Abdul Malik, diretor da Ag\u00eancia de Busca e Resgate de Padang. &#8220;Encontramos 14 pessoas, 3 com vida, e 11 estavam mortas&#8221;, relatou Malik.<\/p>\n<p>Os tr\u00eas sobreviventes foram encontrados nas proximidades da cratera, &#8220;em estado debilitado, alguns com queimaduras&#8221;, de acordo com o diretor. As equipes de resgate trabalharam incansavelmente durante a noite para prestar assist\u00eancia aos montanhistas, conforme comunicado da ag\u00eancia de conserva\u00e7\u00e3o ambiental de Sumatra Ocidental.<\/p>\n<p>O Monte Marapi, situado na ilha de Sumatra, com 2.891 metros de altura, entrou em erup\u00e7\u00e3o no domingo, \u00e0s 14h54 locais (4h54 de Bras\u00edlia), gerando uma coluna de cinzas que alcan\u00e7ou 3 km de altura. A situa\u00e7\u00e3o permanece em constante monitoramento, enquanto as autoridades coordenam esfor\u00e7os para encontrar os desaparecidos e prestar aux\u00edlio \u00e0s v\u00edtimas e familiares afetados por essa trag\u00e9dia vulc\u00e2nica.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mt-1 flex justify-start gap-3 empty:hidden\">\n<div class=\"text-gray-400 flex self-end lg:self-center justify-center lg:justify-start mt-0 gap-1 visible\"><button class=\"flex items-center gap-1.5 rounded-md p-1 pl-0 text-xs hover:text-gray-950 dark:text-gray-400 dark:hover:text-gray-200 disabled:dark:hover:text-gray-400 md:invisible md:group-hover:visible md:group-[.final-completion]:visible\"><\/button><\/p>\n<div class=\"flex gap-1\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/img.r7.com\/images\/vulcao-indonesia-04122023094828542?dimensions=771x420&amp;no_crop=true\" alt=\"No momento da erup\u00e7\u00e3o, neste domingo (3), 75 pessoas estavam no local, e 26 n\u00e3o foram resgatadas a tempo, informou Abdul Malik, diretor da Ag\u00eancia de Busca e Resgate de Padang. \" width=\"422\" height=\"281\" \/><\/div>\n<div class=\"flex items-center gap-1.5 text-xs\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"w-full pt-2 md:pt-0 dark:border-white\/20 md:border-transparent md:dark:border-transparent md:w-[calc(100%-.5rem)]\">\n<form class=\"stretch mx-2 flex flex-row gap-3 last:mb-2 md:mx-4 md:last:mb-6 lg:mx-auto lg:max-w-2xl xl:max-w-3xl\">\n<div class=\"relative flex h-full flex-1 items-stretch md:flex-col\">\n<div class=\"flex w-full items-center\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/img.r7.com\/images\/vulcao-indonesia-04122023094828364?dimensions=771x420&amp;no_crop=true\" alt=\"Os tr\u00eas sobreviventes foram resgatados perto da cratera \" width=\"420\" height=\"280\" \/><\/div>\n<\/div>\n<\/form>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pelo menos 11 pessoas perderam a vida e outras 12 est\u00e3o desaparecidas ap\u00f3s a erup\u00e7\u00e3o do vulc\u00e3o Marapi, localizado na regi\u00e3o oeste da Indon\u00e9sia. Os servi\u00e7os de emerg\u00eancia confirmaram a situa\u00e7\u00e3o nesta segunda-feira (4), ap\u00f3s uma noite intensa de buscas, que resultaram no resgate de tr\u00eas montanhistas. No momento da erup\u00e7\u00e3o, ocorrida no domingo (3), &hellip;<\/p>\n","protected":false},"author":3,"featured_media":10069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[27],"tags":[],"_links":{"self":[{"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/posts\/10068"}],"collection":[{"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/comments?post=10068"}],"version-history":[{"count":1,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/posts\/10068\/revisions"}],"predecessor-version":[{"id":10070,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/posts\/10068\/revisions\/10070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/media\/10069"}],"wp:attachment":[{"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/media?parent=10068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/categories?post=10068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/tags?post=10068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}