{"id":21008,"date":"2026-07-15T12:45:07","date_gmt":"2026-07-15T15:45:07","guid":{"rendered":"https:\/\/www.didasantos.com.br\/v1\/?p=21008"},"modified":"2026-07-15T12:45:07","modified_gmt":"2026-07-15T15:45:07","slug":"nota-de-falecimento-25","status":"publish","type":"post","link":"https:\/\/www.didasantos.com.br\/v1\/2026\/07\/15\/nota-de-falecimento-25\/","title":{"rendered":"Nota de Falecimento"},"content":{"rendered":"<p>\u00c9 com profundo pesar que comunicamos o falecimento de Guiomar Rosa de Souza, aos 56 anos, moradora da Vila Am\u00e9rica.O corpo est\u00e1 sendo velado na Rua Francisco Miranda, casa 4, Vila Am\u00e9rica.<\/p>\n<p>A comunidade da Vila Am\u00e9rica e o Blog do Dida Santos expressam seus mais sinceros sentimentos de solidariedade \u00e0 fam\u00edlia e amigos neste momento de dor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 com profundo pesar que comunicamos o falecimento de Guiomar Rosa de Souza, aos 56 anos, moradora da Vila Am\u00e9rica.O corpo est\u00e1 sendo velado na Rua Francisco Miranda, casa 4, Vila Am\u00e9rica. A comunidade da Vila Am\u00e9rica e o Blog do Dida Santos expressam seus mais sinceros sentimentos de solidariedade \u00e0 fam\u00edlia e amigos neste &hellip;<\/p>\n","protected":false},"author":3,"featured_media":21009,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[22],"tags":[],"_links":{"self":[{"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/posts\/21008"}],"collection":[{"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/comments?post=21008"}],"version-history":[{"count":1,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/posts\/21008\/revisions"}],"predecessor-version":[{"id":21010,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/posts\/21008\/revisions\/21010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/media\/21009"}],"wp:attachment":[{"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/media?parent=21008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/categories?post=21008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.didasantos.com.br\/v1\/wp-json\/wp\/v2\/tags?post=21008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}